{"id":74724,"date":"2026-06-29T10:38:01","date_gmt":"2026-06-29T08:38:01","guid":{"rendered":"https:\/\/icso.lukasiewicz.gov.pl\/june-internal-seminar\/"},"modified":"2026-06-29T11:42:07","modified_gmt":"2026-06-29T09:42:07","slug":"june-internal-seminar","status":"publish","type":"post","link":"https:\/\/icso.lukasiewicz.gov.pl\/en\/june-internal-seminar\/","title":{"rendered":"June Internal Seminar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"74724\" class=\"elementor elementor-74724 elementor-74709\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2d1c92 e-flex e-con-boxed e-con e-parent\" data-id=\"e2d1c92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5829aef elementor-widget elementor-widget-text-editor\" data-id=\"5829aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The internal seminar held on June 24 focused on highly topical issues related to the digitization of the chemical sciences. Dawid Marondel, head of the Advanced Digital Technologies Research Group, gave a presentation titled \u201cAI and Digital Technologies in Chemical Research\u2014Opportunities, Limitations, and Practical Applications,\u201d demonstrating that digital technologies and artificial intelligence can genuinely support R&#038;D work, provided they are used thoughtfully and appropriately. As with many tools, careless use of AI can do more harm than good, but awareness of the risks, adherence to best practices, and guidance from those familiar with how artificial intelligence works can minimize these risks.  <\/p><p>In the second part of the meeting, Aleksander Adamczyk presented the topic \u201cWhen Computers Control Chemistry,\u201d discussing the benefits and risks arising from the increasing digitization of research equipment. Cyberterrorist attacks\u2014exploiting human error or negligence, as well as software vulnerabilities\u2014can, in such situations, result not only in the falsification of research data but also in a real, physical threat to facility staff and bystanders. A shift in mindset is necessary, along with careful planning of cybersecurity for research, but above all, increased vigilance on the part of everyone involved in the process.  <\/p><p>Both topics presented sparked a lively discussion after the presentations ended, demonstrating just how important the issues raised were.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c11bf0a e-flex e-con-boxed e-con e-parent\" data-id=\"c11bf0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-795756f elementor-widget elementor-widget-image\" data-id=\"795756f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-1024x683.jpg\" class=\"attachment-large size-large wp-image-74714\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6257-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4351fe e-flex e-con-boxed e-con e-parent\" data-id=\"a4351fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-157a971 elementor-widget elementor-widget-image\" data-id=\"157a971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-1024x683.jpg\" class=\"attachment-large size-large wp-image-74715\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6260-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05ee408 e-flex e-con-boxed e-con e-parent\" data-id=\"05ee408\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61e4406 elementor-widget elementor-widget-image\" data-id=\"61e4406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"580\" height=\"870\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-683x1024.jpg\" class=\"attachment-large size-large wp-image-74716\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-683x1024.jpg 683w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-200x300.jpg 200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-768x1152.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-1024x1536.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-1365x2048.jpg 1365w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-1200x1800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-1980x2970.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-16x24.jpg 16w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-24x36.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-32x48.jpg 32w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6262-scaled.jpg 1707w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a06a7d8 elementor-widget elementor-widget-image\" data-id=\"a06a7d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-1024x683.jpg\" class=\"attachment-large size-large wp-image-74717\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6278-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3abbcd2 e-flex e-con-boxed e-con e-parent\" data-id=\"3abbcd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-501513f elementor-widget elementor-widget-image\" data-id=\"501513f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-1024x683.jpg\" class=\"attachment-large size-large wp-image-74718\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6279-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f42e85 e-flex e-con-boxed e-con e-parent\" data-id=\"1f42e85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-afe28c3 elementor-widget elementor-widget-image\" data-id=\"afe28c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-1024x683.jpg\" class=\"attachment-large size-large wp-image-74719\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6289-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eacf3f3 e-flex e-con-boxed e-con e-parent\" data-id=\"eacf3f3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-550850c elementor-widget elementor-widget-image\" data-id=\"550850c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-1024x683.jpg\" class=\"attachment-large size-large wp-image-74720\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6293-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9046ca2 e-flex e-con-boxed e-con e-parent\" data-id=\"9046ca2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5eff2 elementor-widget elementor-widget-image\" data-id=\"5e5eff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-1024x683.jpg\" class=\"attachment-large size-large wp-image-74721\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6305-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f0c2e1 e-flex e-con-boxed e-con e-parent\" data-id=\"1f0c2e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-041c520 elementor-widget elementor-widget-image\" data-id=\"041c520\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"387\" src=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-1024x683.jpg\" class=\"attachment-large size-large wp-image-74722\" alt=\"\" srcset=\"https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-1024x683.jpg 1024w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-300x200.jpg 300w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-768x512.jpg 768w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-1536x1024.jpg 1536w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-2048x1365.jpg 2048w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-1200x800.jpg 1200w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-1980x1320.jpg 1980w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-24x16.jpg 24w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-36x24.jpg 36w, https:\/\/icso.lukasiewicz.gov.pl\/wp-content\/uploads\/sites\/34\/2026\/06\/IMG_6295-48x32.jpg 48w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>The internal seminar held on June 24 focused on highly topical issues related to the digitization of the chemical sciences. Dawid Marondel, head of the Advanced Digital Technologies Research Group, gave a presentation titled \u201cAI and Digital Technologies in Chemical Research\u2014Opportunities, Limitations, and Practical Applications,\u201d demonstrating that digital technologies and artificial intelligence can genuinely support [&hellip;]<\/p>\n","protected":false},"author":232,"featured_media":74723,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","inline_featured_image":false,"footnotes":""},"categories":[1046],"tags":[],"class_list":["post-74724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":{"czas_czytania":"3"},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:29:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/posts\/74724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/users\/232"}],"replies":[{"embeddable":true,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/comments?post=74724"}],"version-history":[{"count":3,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/posts\/74724\/revisions"}],"predecessor-version":[{"id":74732,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/posts\/74724\/revisions\/74732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/media\/74723"}],"wp:attachment":[{"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/media?parent=74724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/categories?post=74724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/icso.lukasiewicz.gov.pl\/en\/wp-json\/wp\/v2\/tags?post=74724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}